{"id":24496,"date":"2024-10-13T01:42:04","date_gmt":"2024-10-13T01:42:04","guid":{"rendered":"https:\/\/bcmimprovement.com\/site1\/producto\/camara-ip-domo-antivandalica-dahua-technology-dh-ipc-hdbw2831en-s-0280b-s2\/"},"modified":"2024-10-13T01:42:11","modified_gmt":"2024-10-13T01:42:11","slug":"camara-ip-domo-antivandalica-dahua-technology-dh-ipc-hdbw2831en-s-0280b-s2","status":"publish","type":"product","link":"https:\/\/bcmimprovement.com\/site1\/producto\/camara-ip-domo-antivandalica-dahua-technology-dh-ipc-hdbw2831en-s-0280b-s2\/","title":{"rendered":"C\u00e1mara IP Domo Antivandalica Dahua Technology DH-IPC-HDBW2831EN-S-0280B-S2"},"content":{"rendered":"<p>C\u00e1mara IP Domo Antivandalica Dahua Technology DH-IPC-HDBW2831EN-S-0280B-S2 &#8211;<\/p>\n<p>Colocaci\u00f3n soportada: Interior<br \/>\nM\u00e1xima resoluci\u00f3n: 2688 x 1520 Pixeles<br \/>\nFormato de v\u00eddeo soportado: 720p,1080p<br \/>\nMegapixeles: 4 MP<br \/>\nTipo de montaje: Techo\/Pared\/Poste<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>C\u00e1mara IP Domo Antivandalica Dahua Technology DH-IPC-HDBW2831EN-S-0280B-S2 &#8211;<\/strong><\/p>\n","protected":false},"featured_media":24497,"comment_status":"closed","ping_status":"open","template":"","meta":[],"product_cat":[209,195],"product_tag":[],"class_list":{"0":"post-24496","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-camara-domo-ip","7":"product_cat-video-vigilancia","9":"first","10":"instock","11":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/bcmimprovement.com\/site1\/wp-json\/wp\/v2\/product\/24496","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bcmimprovement.com\/site1\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bcmimprovement.com\/site1\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/bcmimprovement.com\/site1\/wp-json\/wp\/v2\/comments?post=24496"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bcmimprovement.com\/site1\/wp-json\/wp\/v2\/media\/24497"}],"wp:attachment":[{"href":"https:\/\/bcmimprovement.com\/site1\/wp-json\/wp\/v2\/media?parent=24496"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bcmimprovement.com\/site1\/wp-json\/wp\/v2\/product_cat?post=24496"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bcmimprovement.com\/site1\/wp-json\/wp\/v2\/product_tag?post=24496"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}