{"id":24498,"date":"2024-10-13T01:42:04","date_gmt":"2024-10-13T01:42:04","guid":{"rendered":"https:\/\/bcmimprovement.com\/site1\/producto\/camara-ip-bala-dahua-technology-dh-ipc-hfw3441e-as-s2\/"},"modified":"2024-10-13T01:42:12","modified_gmt":"2024-10-13T01:42:12","slug":"camara-ip-bala-dahua-technology-dh-ipc-hfw3441e-as-s2","status":"publish","type":"product","link":"https:\/\/bcmimprovement.com\/site1\/producto\/camara-ip-bala-dahua-technology-dh-ipc-hfw3441e-as-s2\/","title":{"rendered":"C\u00e1mara IP Bala Dahua Technology DH-IPC-HFW3441E-AS-S2"},"content":{"rendered":"<p>C\u00e1mara IP Bala Dahua Technology DH-IPC-HFW3441E-AS-S2 &#8211;<\/p>\n<p>Tecnolog\u00eda de conectividad: Al\u00e1mbrico<br \/>\nM\u00e1xima resoluci\u00f3n: 2688 x 1520 Pixeles<br \/>\nTotal de megapixeles: 4 MP<br \/>\nTipo de montaje: Techo \/ Pared<br \/>\nFormatos de v\u00eddeo compatibles: H.264+, H.265+<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>C\u00e1mara IP Bala Dahua Technology DH-IPC-HFW3441E-AS-S2 &#8211;<\/strong><\/p>\n","protected":false},"featured_media":24499,"comment_status":"closed","ping_status":"open","template":"","meta":[],"product_cat":[213,195],"product_tag":[],"class_list":{"0":"post-24498","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-camara-bala-ip","7":"product_cat-video-vigilancia","9":"first","10":"instock","11":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/bcmimprovement.com\/site1\/wp-json\/wp\/v2\/product\/24498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bcmimprovement.com\/site1\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/bcmimprovement.com\/site1\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/bcmimprovement.com\/site1\/wp-json\/wp\/v2\/comments?post=24498"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bcmimprovement.com\/site1\/wp-json\/wp\/v2\/media\/24499"}],"wp:attachment":[{"href":"https:\/\/bcmimprovement.com\/site1\/wp-json\/wp\/v2\/media?parent=24498"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/bcmimprovement.com\/site1\/wp-json\/wp\/v2\/product_cat?post=24498"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/bcmimprovement.com\/site1\/wp-json\/wp\/v2\/product_tag?post=24498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}